{"id":1868,"date":"2021-06-19T14:35:52","date_gmt":"2021-06-19T10:35:52","guid":{"rendered":"http:\/\/autobox.ge\/?page_id=1868"},"modified":"2021-07-15T05:01:32","modified_gmt":"2021-07-15T01:01:32","slug":"projects","status":"publish","type":"page","link":"https:\/\/poolandspa.ge\/en\/projects\/","title":{"rendered":"Projects"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]<div class=\"qodef-portfolio-list-holder qodef-grid-list qodef-grid-masonry-list qodef-disable-bottom-space qodef-pl-masonry qodef-three-columns qodef-tiny-space qodef-pl-standard-shader    qodef-pl-pag-no-pagination     \"  data-type=masonry data-number-of-columns=three data-space-between-items=tiny data-number-of-items=-1 data-image-proportions=full data-enable-fixed-proportions=no data-enable-image-shadow=no data-orderby=date data-order=ASC data-item-style=standard-shader data-enable-title=yes data-title-tag=h3 data-enable-category=yes data-enable-count-images=yes data-enable-excerpt=no data-excerpt-length=20 data-pagination-type=no-pagination data-filter=no data-filter-order-by=name data-enable-article-animation=no data-portfolio-slider-on=no data-enable-loop=yes data-enable-autoplay=yes data-slider-speed=5000 data-slider-speed-animation=600 data-enable-navigation=yes data-enable-pagination=yes data-max-num-pages=0 data-next-page=2>\n\t\t<div class=\"qodef-pl-inner qodef-outer-space qodef-masonry-list-wrapper clearfix\">\n\t\t<div class=\"qodef-masonry-grid-sizer\"><\/div>\n\t\t<div class=\"qodef-masonry-grid-gutter\"><\/div>\n\t\t<article class=\"qodef-pl-item qodef-item-space  post-1900 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"588\" height=\"441\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-001.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-001.jpg 588w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-001-300x225.jpg 300w\" sizes=\"auto, (max-width: 588px) 100vw, 588px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tPublic and Kid\u2019s Pools in Hotel \u201eElita\u201c Ureki, Georgia\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/public-and-kid-s-pools-in-hotel-elita-ureki-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1903 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"604\" height=\"440\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-003.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-003.jpg 604w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-003-300x219.jpg 300w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tRehabilitation of technologies of waves pool in Aquapark \u201cGinoparadise\u201d Tbilisi, Georgia\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/rehabilitation-of-technologies-of-waves-pool-in-aquapark-ginoparadise-tbilisi-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1906 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1103\" height=\"446\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-005.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-005.jpg 1103w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-005-300x121.jpg 300w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-005-1024x414.jpg 1024w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-005-768x311.jpg 768w\" sizes=\"auto, (max-width: 1103px) 100vw, 1103px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tOutdoor Public Swimming pool with Bar in aquapark \u201cGinoparadise\u201d Tbilisi Georgia\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/outdoor-public-swimming-pool-with-bar-in-aquapark-ginoparadise-tbilisi-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1908 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"622\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-006.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-006.jpg 1280w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-006-300x146.jpg 300w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-006-1024x498.jpg 1024w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-006-768x373.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tOutdoor Swimming pool&#038;kids pool in aquapark \u201cGinoparadise\u201d Tbilisi Georgia\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/outdoor-swimming-pool-kids-pool-in-aquapark-ginoparadise-tbilisi-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1910 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"657\" height=\"308\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-007.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-007.jpg 657w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-007-300x141.jpg 300w\" sizes=\"auto, (max-width: 657px) 100vw, 657px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tArkadia Residence Ureki Georgia\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/arkadia-residence-ureki-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1912 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"391\" height=\"600\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-008.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-008.jpg 391w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-008-196x300.jpg 196w\" sizes=\"auto, (max-width: 391px) 100vw, 391px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tOutdoor Slides in aquapark \u201cGinoparadise\u201d Tbilisi Georgia\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/outdoor-slides-in-aquapark-ginoparadise-tbilisi-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1916 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-proeqtebi\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"640\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-012-rotated.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-012-rotated.jpg 480w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-012-225x300.jpg 225w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tPublic Swimming Pools in Municipal Sport Hall Tbilisi city, Georgia\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/public-swimming-pools-in-municipal-sport-hall-tbilisi-city-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1920 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"555\" height=\"269\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-020.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-020.jpg 555w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-020-300x145.jpg 300w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tHotel AMBASSADORI Goderdzi Ski Resort\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/hotel-ambassadori-goderdzi-ski-resort\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1925 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"477\" height=\"358\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-023.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-023.jpg 477w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-023-300x225.jpg 300w\" sizes=\"auto, (max-width: 477px) 100vw, 477px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tSwimming pool and Spa Chateau \u201eSchuchman wines Georgia\u201c Kisiskhevi,Telavi, Georgia\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/swimming-pool-and-spa-chateau-schuchman-wines-georgia-kisiskhevi-telavi-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1937 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"565\" height=\"376\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-032.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-032.jpg 565w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-032-300x200.jpg 300w\" sizes=\"auto, (max-width: 565px) 100vw, 565px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tSwimming pool in Hotel \u201eGino wellness Mtskheta\u201c Mtskheta city, Georgia\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/swimming-pool-in-hotel-gino-wellness-mtskheta-mtskheta-city-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1940 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"773\" height=\"530\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-038.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-038.jpg 773w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-038-300x206.jpg 300w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-038-768x527.jpg 768w\" sizes=\"auto, (max-width: 773px) 100vw, 773px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tHotel \u201eBILTMORE TBILISI\u201d Public vitality pool and Spa\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/hotel-biltmore-tbilisi-public-vitality-pool-and-spa\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1959 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-proeqtebi\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"335\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-051.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-051.jpg 595w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-051-300x169.jpg 300w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tHotel \u201cWhite House\u201d Ureki Georgia\u201d\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/hotel-white-house-ureki-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1962 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"590\" height=\"443\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-053.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-053.jpg 590w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-053-300x225.jpg 300w\" sizes=\"auto, (max-width: 590px) 100vw, 590px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tHotel \u201cAstoria\u201d Tbilisi Georgia\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/hotel-astoria-tbilisi-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1965 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"474\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-055.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-055.jpg 632w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-055-300x225.jpg 300w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tHotel \u201cBella Costa\u201d Batumi Georgia\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/hotel-bella-costa-batumi-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1968 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"609\" height=\"456\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-057.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-057.jpg 609w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-057-300x225.jpg 300w\" sizes=\"auto, (max-width: 609px) 100vw, 609px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tHotel \u201cParagraph Resort &#038; Spa Shekvetili Autograph Collection\u201d by Marriott Shekvetili Georgia\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/hotel-paragraph-resort-spa-shekvetili-autograph-collection-by-marriott-shekvetili-georgia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1972 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"608\" height=\"456\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-061.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-061.jpg 608w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-061-300x225.jpg 300w\" sizes=\"auto, (max-width: 608px) 100vw, 608px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tKid\u2019s Pool and Pool with slides\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/kid-s-pool-and-pool-with-slides\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1978 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"466\" height=\"350\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-093.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-093.jpg 466w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-093-300x225.jpg 300w\" sizes=\"auto, (max-width: 466px) 100vw, 466px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tTelescopic Enclosures\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/telescopic-enclosures\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-1988 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"452\" height=\"603\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-105.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-105.jpg 452w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-105-225x300.jpg 225w\" sizes=\"auto, (max-width: 452px) 100vw, 452px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tPrivate swimming pools\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/private-swimming-pools\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"qodef-pl-item qodef-item-space  post-2007 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry\">\n\t<div class=\"qodef-pl-item-inner\">\n\t\t<div class=\"qodef-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"425\" src=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-117.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-117.jpg 567w, https:\/\/poolandspa.ge\/wp-content\/uploads\/2021\/07\/image-117-300x225.jpg 300w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/div>\n<div class=\"qodef-pli-text-holder\" >\n\t<div class=\"qodef-pli-text-wrapper\">\n\t\t<div class=\"qodef-pli-text\">\n\t\t\t\t<h3 itemprop=\"name\" class=\"qodef-pli-title entry-title\" >\n\t\tDecking\t<\/h3>\n\n\t\t\t\t\t<div class=\"qodef-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"qodef-pli-category\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-category\/proeqtebi\/\">\u10de\u10e0\u10dd\u10d4\u10e5\u10e2\u10d4\u10d1\u10d8<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"qodef-pli-link qodef-block-drag-link\" href=\"https:\/\/poolandspa.ge\/en\/portfolio-item\/decking\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article>\t<\/div>\n\t\n\t<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1868","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/poolandspa.ge\/en\/wp-json\/wp\/v2\/pages\/1868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poolandspa.ge\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/poolandspa.ge\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/poolandspa.ge\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/poolandspa.ge\/en\/wp-json\/wp\/v2\/comments?post=1868"}],"version-history":[{"count":5,"href":"https:\/\/poolandspa.ge\/en\/wp-json\/wp\/v2\/pages\/1868\/revisions"}],"predecessor-version":[{"id":2379,"href":"https:\/\/poolandspa.ge\/en\/wp-json\/wp\/v2\/pages\/1868\/revisions\/2379"}],"wp:attachment":[{"href":"https:\/\/poolandspa.ge\/en\/wp-json\/wp\/v2\/media?parent=1868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}